{"id":1885,"date":"2025-03-18T18:36:29","date_gmt":"2025-03-18T17:36:29","guid":{"rendered":"https:\/\/latrencadora.com\/avellana-redonda-tostada-1000-g\/"},"modified":"2026-04-20T14:18:59","modified_gmt":"2026-04-20T13:18:59","slug":"avellana-redonda-tostada-1000-g","status":"publish","type":"product","link":"https:\/\/latrencadora.com\/es\/avellana-redonda-tostada-1000-g\/","title":{"rendered":"Avellana Redonda Tostada 1000 g"},"content":{"rendered":"<p><strong>Compra Inteligente:<\/strong> Comprando estos productos est\u00e1s invirtiendo en tu tierra, su paisaje y su gente.<\/p>\n<p>\u00abTodos los productos los hacemos \u00edntegramente en nuestro obrador de El Rourell (Alt Camp)\u00bb<\/p>\n<p><strong>Procedencia: <\/strong>mayoritariamente Alt y Baix Camp y alrededores (Tarragona) o Comarca de la Selva (Girona). Puntualmente puede haber avellanas del Vall\u00e8s Oriental. <\/p>\n<p>Trazabilidad: Avellanas seleccionadas exclusivamente de las mejores cosechas de nuestra casa.<\/p>\n<p>Cada partida, est\u00e1 codificada y contiene todos los par\u00e1metros (fecha de entrada, variedad, procedencia y par\u00e1metros de calidad. De forma exclusiva ya diferencia de lo que se hace habitualmente, estas partidas se mantienen separadas a la espera de pedido. <\/p>\n<p>\u00abS\u00f3lo las mejores partidas garantizan siempre, el mejor producto terminado\u00bb<\/p>\n<p><strong>Descascarillado: <\/strong>Proceso de separaci\u00f3n del grano del caparaz\u00f3n hecho por m\u00e9todo de gravedad y presi\u00f3n, no por rozamiento.<\/p>\n<p><strong>Conservaci\u00f3n de las propiedades organol\u00e9pticas <\/strong><\/p>\n<p>Cuidamos el intervalo de tiempo entre el descascarillado y el envasado. La protecci\u00f3n natural de la avellana es su caparaz\u00f3n, cuando se descascarilla (separamos el caparaz\u00f3n del grano), se inicia el proceso de oxidaci\u00f3n del grano, incrementando exponencialmente el % de acidez en el aceite del fruto. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Variedad: Tonda (&lt;0,1% otras variedades). <em>Cultivada en nuestra casa.<\/em><\/p>\n<p>Tostado por m\u00e9todo artesanal rotativo, a baja temperatura. Frecuencia semanal (fecha de tostado estampado en cada bolsa) <\/p>\n<p>Conservaci\u00f3n: Evitar luz solar y en lugar fresco<\/p>\n<p>Recomendaci\u00f3n de consumo: Una vez abierto se aconseja consumirlo en 3 d\u00edas (Las propiedades organol\u00e9pticas excepcionales de la avellana tostada se pierden exponencialmente con el tiempo) <\/p>\n","protected":false},"featured_media":772,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[55,43],"product_tag":[],"alergens":[63],"class_list":["post-1885","product","type-product","status-publish","has-post-thumbnail","product_cat-avellana-tostada","product_cat-avellanas","alergens-sin-gluten","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product\/1885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/comments?post=1885"}],"version-history":[{"count":3,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product\/1885\/revisions"}],"predecessor-version":[{"id":2922,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product\/1885\/revisions\/2922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/media\/772"}],"wp:attachment":[{"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/media?parent=1885"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product_brand?post=1885"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product_cat?post=1885"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/product_tag?post=1885"},{"taxonomy":"alergens","embeddable":true,"href":"https:\/\/latrencadora.com\/es\/wp-json\/wp\/v2\/alergens?post=1885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}